{"id":181518,"date":"2023-10-01T01:28:12","date_gmt":"2023-10-01T06:28:12","guid":{"rendered":"https:\/\/socialnewsdaily.com\/181518\/cuantas-personas-ven-los-eventos-deportivos\/"},"modified":"2022-03-09T10:51:37","modified_gmt":"2022-03-09T09:51:37","slug":"cuantas-personas-ven-los-eventos-deportivos","status":"publish","type":"post","link":"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/","title":{"rendered":"\u00bfCu\u00e1ntas personas ven los eventos deportivos?"},"content":{"rendered":"<p>El sector de los deportes electr\u00f3nicos siempre ha crecido r\u00e1pidamente y, a pesar de la pandemia del COVID-19, las cifras en 2021 son m\u00e1s altas que nunca. Algunos eventos deportivos clave han contribuido a este \u00e9xito, as\u00ed como una gran cantidad de contenidos creativos que crean expectaci\u00f3n y aumentan los ingresos de los deportes electr\u00f3nicos. \u00a1Vamos a sumergirnos en todos ellos!<!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Espectadores_de_los_deportes_electronicos_cifras_en_2021\" >Espectadores de los deportes electr\u00f3nicos: cifras en 2021<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Tasa_de_crecimiento_acelerada_Que_significa\" >Tasa de crecimiento acelerada: Qu\u00e9 significa<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Los_mejores_torneos_de_esports_de_este_ano_hasta_ahora\" >Los mejores torneos de esports de este a\u00f1o (hasta ahora)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Ligas_regionales_de_League_of_Legends_LCS_LEC_LCK_LPL_entre_otras\" >Ligas regionales de League of Legends (LCS, LEC, LCK, LPL, entre otras)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Serie_Mundial_de_Fuego_Libre_2021_Singapur\" >Serie Mundial de Fuego Libre 2021 Singapur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Dota_2_WePlay_AniMajor\" >Dota 2 WePlay AniMajor<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Los_torneos_mas_esperados_que_tendran_lugar_en_2021\" >Los torneos m\u00e1s esperados que tendr\u00e1n lugar en 2021<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#La_Internacional_10\" >La Internacional 10<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#Campeonato_Mundial_de_League_of_Legends\" >Campeonato Mundial de League of Legends<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#PGL_Estocolmo_Mayor\" >PGL Estocolmo Mayor<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#%C2%BFDonde_se_reune_el_publico_Las_principales_plataformas_de_streaming\" >\u00bfD\u00f3nde se re\u00fane el p\u00fablico? Las principales plataformas de streaming<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/socialnewsdaily.com\/es\/cuantas-personas-ven-los-eventos-deportivos\/#El_futuro_de_la_industria_de_los_deportes_electronicos\" >El futuro de la industria de los deportes electr\u00f3nicos<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Espectadores_de_los_deportes_electronicos_cifras_en_2021\"><\/span>Espectadores de los deportes electr\u00f3nicos: cifras en 2021<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ver eventos de esports se ha convertido recientemente en una actividad de masas: aunque antes se consideraba un pasatiempo muy nicho, ni siquiera comparable a los deportes tradicionales, los aficionados a los esports hacen ahora tanto ruido que la industria del entretenimiento est\u00e1 seriamente influenciada por el p\u00fablico de los esports. Este movimiento comenz\u00f3 hace mucho tiempo, pero no ha sido hasta los \u00faltimos cinco o diez a\u00f1os cuando los deportes electr\u00f3nicos competitivos han empezado a conquistar realmente el mundo. La audiencia comenz\u00f3 a salirse de la gr\u00e1fica, con m\u00e1s de un mill\u00f3n de personas que ven simult\u00e1neamente el contenido de los deportes electr\u00f3nicos profesionales, los estadios se agotan y los eventos de primer nivel se convierten en megaproducciones, lo que aumenta a\u00fan m\u00e1s los ingresos de los deportes electr\u00f3nicos y re\u00fane a una audiencia mundial de deportes electr\u00f3nicos. La audiencia <em>in loco <\/em>(f\u00edsica) de League of Legends en 2018, por ejemplo, fue mayor que la audiencia de la NBA; este hecho por s\u00ed solo puede dar una idea de lo enormes que son las posibilidades del mercado de los deportes electr\u00f3nicos.<\/p>\n<p>La pandemia del COVID-19 afect\u00f3 a muchas industrias y, a primera vista, el mercado de los deportes electr\u00f3nicos no fue una excepci\u00f3n. Muchos torneos importantes tuvieron que ser pospuestos, cancelados o trasladados, lo que inmediatamente perjudic\u00f3 a la audiencia de los deportes electr\u00f3nicos, preocup\u00f3 a las partes interesadas y tambi\u00e9n a los jugadores y al personal.<\/p>\n<p>Pero el mercado de los deportes electr\u00f3nicos reaccion\u00f3 bien tras los cambios del a\u00f1o pasado, tanto en t\u00e9rminos de ingresos como de audiencia. Seg\u00fan la agencia de an\u00e1lisis Statista, en 2021, la previsi\u00f3n de audiencia total de los eventos de esports es de 474 millones de personas, lo que supone un crecimiento de m\u00e1s del 8% si se compara con 2020. Adem\u00e1s, un estudio de Newzoo muestra que los ingresos de los deportes electr\u00f3nicos van a alcanzar los 1.100 millones de d\u00f3lares este a\u00f1o, aprovechando la reciente inversi\u00f3n en deportes electr\u00f3nicos de empresas l\u00edderes como Tencent (propietaria de Riot Games).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93417 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_global-esports-audience.jpg\" alt=\"\" width=\"1000\" height=\"400\"><\/p>\n<p><em>  Fuente de datos: Statista<\/em><\/p>\n<p>Otra cosa que tenemos que considerar son las perspectivas de los deportes electr\u00f3nicos para m\u00f3viles. En julio de 2021, el evento m\u00e1s visto fue el PUBG Mobile&#8217;s World Invitational 2021, con un impresionante resultado de m\u00e1s de un mill\u00f3n de picos de audiencia, y en mayo (2021), las Free Fire World Series 2021 Singapur hicieron historia y se convirtieron en el evento m\u00e1s visto de la historia de los juegos para m\u00f3viles (y de los juegos en general, si obviamos las cifras de Riot Games), con un pico de  <strong>m\u00e1s de cinco millones de espectadores simult\u00e1neos.  <\/strong>Esos torneos son tan importantes para el p\u00fablico de los deportes electr\u00f3nicos que las cifras podr\u00edan ser incluso mejores de lo previsto, y juegos como Free Fire representan un nicho en el mercado de los deportes electr\u00f3nicos para pa\u00edses que antes eran menos visibles, como Brasil y la India.<\/p>\n<p>Con un crecimiento tan incre\u00edble, el t\u00e9rmino \u00abacelerado\u00bb no es una hip\u00e9rbole.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Tasa_de_crecimiento_acelerada_Que_significa\"><\/span>Tasa de crecimiento acelerada: Qu\u00e9 significa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La industria del juego tiene muchas formas de generar ingresos, pero el sector del entretenimiento tiene ideas y escenarios de crecimiento casi infinitos. Por eso, los entusiastas de los deportes electr\u00f3nicos siempre separan el mercado del juego del mercado de los deportes electr\u00f3nicos: las ideas de activaci\u00f3n de la marca y los ingresos de los eventos de deportes electr\u00f3nicos de vanguardia var\u00edan mucho.<\/p>\n<p>El marketing de los deportes electr\u00f3nicos aprovecha casi todos los aspectos de un evento. Desde los espectadores ocasionales hasta los compradores empedernidos de mercanc\u00eda, todos buscan sumergirse en sus pasiones, por lo que los deportes electr\u00f3nicos tienen que ver con las emociones, la emoci\u00f3n y la diversi\u00f3n. Los deportes electr\u00f3nicos pueden ofrecer un sinf\u00edn de eventos para mantener a la audiencia entretenida: los intereses de la base de espectadores de los deportes electr\u00f3nicos pueden ir desde las ferias de juegos hasta los eventos m\u00e1s importantes, y la asistencia puede ser tanto f\u00edsica (como se ha mencionado, superando los n\u00fameros de las ligas deportivas tradicionales como la NBA en los tiempos anteriores al brote de COVID-19) como a trav\u00e9s de plataformas en l\u00ednea, con el plus de que \u00e9stas proporcionan un buen nivel de inmersi\u00f3n, ya que el valor de producci\u00f3n suele ser fuera de serie.<\/p>\n<p>Por lo tanto, si tenemos en cuenta todos los datos mencionados anteriormente, desde los espectadores hasta los ingresos de los deportes electr\u00f3nicos, todo se est\u00e1 disparando. No hay retrocesos en las cifras absolutas de los deportes electr\u00f3nicos, lo que da un poco de miedo: es una industria en una curva de crecimiento constante. Incluso ante grandes adversidades como la pandemia, de alguna manera los ingresos sobrevivieron y aumentaron, y lo mismo ocurri\u00f3 con la audiencia total de los deportes electr\u00f3nicos. M\u00e1s de un mill\u00f3n de entusiastas de los deportes electr\u00f3nicos ven cada evento por t\u00e9rmino medio, lo que hace que lo que antes era s\u00f3lo un nicho, un sector \u00abemergente\u00bb del entretenimiento, se convierta en una corriente principal.<\/p>\n<p>Todo esto ha ocurrido a muy corto plazo en comparaci\u00f3n con otros sectores establecidos de nuestra econom\u00eda. Desde la popularizaci\u00f3n de juegos como Starcraft II hasta los 474 millones de espectadores totales, s\u00f3lo ha pasado algo m\u00e1s de una d\u00e9cada, y este tremendo crecimiento parece no conocer l\u00edmites en los deportes electr\u00f3nicos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Los_mejores_torneos_de_esports_de_este_ano_hasta_ahora\"><\/span>Los mejores torneos de esports de este a\u00f1o (hasta ahora)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A pesar de que los eventos m\u00e1s importantes se celebraron m\u00e1s tarde en el a\u00f1o (este art\u00edculo se escribi\u00f3 a finales de agosto de 2021), algunos eventos incre\u00edbles siguieron batiendo r\u00e9cords y reunieron a una gran cantidad de p\u00fablico. Algunos de esos eventos tuvieron una producci\u00f3n tan detallada y bien hecha que es l\u00f3gico que figuren en esta secci\u00f3n. Tambi\u00e9n est\u00e1n las tradicionales ligas regionales de League of Legends, que siempre reciben mucha atenci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Ligas_regionales_de_League_of_Legends_LCS_LEC_LCK_LPL_entre_otras\"><\/span>Ligas regionales de League of Legends (LCS, LEC, LCK, LPL, entre otras)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Las ligas regionales de League of Legends son una maravilla para los que les gusta seguir un torneo durante mucho tiempo. En Europa, por ejemplo, hay m\u00e1s de 60.000 en YouTube y m\u00e1s de 100.000 espectadores de media en Twitch. Esas ligas existen desde 2012 (en este formato) y son muy populares desde el principio.<\/p>\n<p>Las nomenclaturas pueden ser un poco m\u00e1s dif\u00edciles de seguir, pero las principales ligas en cuanto a audiencia de los deportes electr\u00f3nicos son la europea (LEC), la norteamericana (LCS), la surcoreana (LCK) y la china (LPL). Se dividen en Split de primavera (equipos que se clasifican para el Mid-Season Invitational, un torneo muy importante) y Split de verano (equipos que se clasifican para el evento de LoL m\u00e1s importante del a\u00f1o, el Campeonato Mundial). Los cinco continentes tienen su liga nacional con diferentes cabezas de serie en esos torneos, lo que convierte a las ligas de LoL en una de las m\u00e1s fuertes en t\u00e9rminos de audiencia global de esports.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Serie_Mundial_de_Fuego_Libre_2021_Singapur\"><\/span>Serie Mundial de Fuego Libre 2021 Singapur<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-93425 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/free-fire-world-series-2021-singapore1-1.jpg\" alt=\"\" width=\"1000\" height=\"400\"><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9dito de la imagen: Garena<\/em><\/p>\n<p>Hola, es hora de jugar con el m\u00f3vil. Free Fire es un \u00e9xito en Am\u00e9rica Latina, China y el Sudeste Asi\u00e1tico, y jugadores de todo el mundo se re\u00fanen para disfrutar de la escena.<\/p>\n<p>Las estad\u00edsticas de los deportes electr\u00f3nicos para m\u00f3viles se est\u00e1n disparando. Free Fire tiene su plataforma de transmisi\u00f3n en vivo (no es exclusiva del juego, pero la mayor\u00eda de los torneos del juego se transmiten all\u00ed) llamada Booyah!, y a trav\u00e9s de ella llega la mayor parte de la audiencia de sus eventos. Sin embargo, la Serie Mundial 2021 de Singapur fue algo fuera de lo com\u00fan. Los datos (de la agencia de an\u00e1lisis Esports Charts) muestran que este es oficialmente el torneo de esports m\u00e1s visto de la historia, sin tener en cuenta las cifras proporcionadas por Riot Games, con 5,4 millones de espectadores m\u00e1ximos. Esas cifras son tan enormes que incluso pueden igualar a algunas megaproducciones deportivas tradicionales.<\/p>\n<p>Y s\u00f3lo podemos esperar m\u00e1s de esta escena, ya que el dinero de los premios sigue aumentando y los juegos (como el propio Free Fire, PUBG mobile y Arena of Value) siguen creciendo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Dota_2_WePlay_AniMajor\"><\/span>Dota 2 WePlay AniMajor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-93420 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_weplay_animajor_day12_40_1.jpg\" alt=\"\" width=\"1000\" height=\"400\"><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9dito de la imagen: <\/em><a href=\"https:\/\/weplayholding.com\/\" target=\"_blank\" rel=\"noopener\">WePlay Holding<\/a><\/p>\n<p>Con un valor de producci\u00f3n demencial, el segundo (y \u00faltimo) major del Dota Pro Circuit (DPC) de este a\u00f1o fue uno de los clasificatorios de \u00faltima oportunidad para el evento de Dota 2 m\u00e1s importante del a\u00f1o: The International. El Major de WePlay fue recibido con mucho bombo y platillo, reuniendo a m\u00e1s de 800.000 espectadores concurrentes &#8211; lo que sit\u00faa al AniMajor de WePlay como el segundo Major de Dota 2 m\u00e1s visto de la historia (casualmente, el primer puesto pertenece a otro Major que tuvo lugar en Kyiv, Ucrania, en 2017).<\/p>\n<p>Los entusiastas de los deportes electr\u00f3nicos comprendieron la importancia de este torneo, ya que estaba en juego la clasificaci\u00f3n para The International: Dota 2 funciona mediante un sistema llamado DPC, y el principal criterio para jugar en el mayor evento es esa clasificaci\u00f3n. El acto se celebr\u00f3 sin presencia de p\u00fablico, pero aun as\u00ed se desarroll\u00f3 con gran \u00e9xito.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Los_torneos_mas_esperados_que_tendran_lugar_en_2021\"><\/span>Los torneos m\u00e1s esperados que tendr\u00e1n lugar en 2021<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Puede que sea un poco injusto, ya que otros eventos tambi\u00e9n lo tienen todo para ser impresionantes, y hay que tener en cuenta que habr\u00e1 muchos torneos interesantes en disciplinas m\u00e1s nuevas, como VALORANT, pero echemos un vistazo a los eventos internacionales m\u00e1s tradicionales que hacen vibrar la escena de los deportes electr\u00f3nicos en vivo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"La_Internacional_10\"><\/span>La Internacional 10<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93415 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_3dota-2-the-international-10.jpg\" alt=\"\" width=\"800\" height=\"400\"><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9dito de la imagen: Valve<\/em><\/p>\n<p>Tras ser aplazado en 2020, Dota 2 The International se convirti\u00f3 en el evento estrella de 2021. Con la mayor bolsa de premios de la historia de los deportes electr\u00f3nicos, de m\u00e1s de 40 millones de d\u00f3lares, la media de espectadores prevista para este evento lo convierte en un aspirante al torneo de Dota 2 m\u00e1s visto de la historia.<\/p>\n<p>Habr\u00e1 que esperar para ver si las estad\u00edsticas siguen el bombo, pero ya hay mucho contenido creado, espectadores ocasionales que lo discuten en foros de profundidad (como Reddit), etc. Todo apunta a que The International 10 es el evento de Dota 2 m\u00e1s exitoso de todos los tiempos.<\/p>\n<p>El evento tendr\u00e1 lugar con el p\u00fablico presente en Bucarest, comenzando el 7 de octubre y terminando el 17 de octubre. No parpadee, o podr\u00eda perderse uno de los eventos de esports m\u00e1s esperados del mundo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Campeonato_Mundial_de_League_of_Legends\"><\/span>Campeonato Mundial de League of Legends<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-93416 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_2021-league-of-legends-world-championship.jpg\" alt=\"\" width=\"1000\" height=\"400\" srcset=\"https:\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_2021-league-of-legends-world-championship.jpg 1000w, https:\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_2021-league-of-legends-world-championship-768x307.jpg 768w, https:\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_2021-league-of-legends-world-championship-150x60.jpg 150w, https:\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_2021-league-of-legends-world-championship-300x120.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9dito de la imagen: Riot Games<\/em><\/p>\n<p>Este evento de deportes electr\u00f3nicos es siempre una tormenta. Las cifras oficiales de Riot Games est\u00e1n rid\u00edculamente por encima de la media cuando se comparan con las de las agencias de an\u00e1lisis, pero las estad\u00edsticas de audiencia, incluso excluyendo China (las agencias no suelen tener acceso a las estad\u00edsticas de China) son incre\u00edblemente enormes.<\/p>\n<p>Este a\u00f1o, los aficionados a los deportes electr\u00f3nicos ya se est\u00e1n mordiendo las u\u00f1as despu\u00e9s de que algunas grandes organizaciones de deportes electr\u00f3nicos, como G2 Esports y Team SoloMid, no se hayan clasificado. Las apuestas son m\u00e1s altas que nunca, y aunque el dinero oficial de los premios est\u00e1 muy lejos de The International (con 2,25 millones de d\u00f3lares), este evento es el que m\u00e1s se ha promocionado. La audiencia mundial de los deportes electr\u00f3nicos podr\u00eda superar los 40 millones de espectadores simult\u00e1neos.<\/p>\n<p>Los derechos medi\u00e1ticos del Campeonato Mundial pertenecen exclusivamente a la empresa LoL.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"PGL_Estocolmo_Mayor\"><\/span>PGL Estocolmo Mayor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93418 aligncenter\" src=\"\/\/socialnewsdaily.com\/wp-content\/uploads\/2021\/10\/rsz_pglstockholmmajor2.jpg\" alt=\"\" width=\"1000\" height=\"400\"><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9dito de la imagen: PGL ESPORTS<\/em><\/p>\n<p>Jugar a Counter-Strike: Global Offensive en una red local es muy diferente de jugarlo en l\u00ednea. Y el PGL Stockholm Major es uno de los primeros torneos offline de Counter-Strike: Global Offensive desde el brote de COVID-19. Eso es suficiente para que los jugadores suden de emoci\u00f3n. \u00bfNo est\u00e1 convencido? Normalmente, el premio en met\u00e1lico de un Major de CS:GO es de un mill\u00f3n de d\u00f3lares. En este caso, redoblaron la apuesta. As\u00ed es: 2 millones de d\u00f3lares. Una gran bolsa, teniendo en cuenta que CS:GO no tiene un \u00abcampeonato mundial\u00bb (aparte de las BLAST Premier World Finals. Sin embargo, la bolsa de premios sigue siendo la misma que en los majors), sino que hay muchos majors en un a\u00f1o.<\/p>\n<p>Los datos muestran que el p\u00fablico de CS:GO no est\u00e1 disminuyendo, a pesar de las condiciones adversas para el juego. Eso s\u00f3lo puede significar una cosa: este torneo romper\u00e1 las tablas, ya que es un hecho conocido que la presencia del p\u00fablico s\u00f3lo a\u00f1ade m\u00e1s picante, si hablamos de un evento de CS:GO.<\/p>\n<p>El mercado de los deportes electr\u00f3nicos y la industria del juego pueden establecer un nuevo est\u00e1ndar a partir de aqu\u00ed. La PGL Stockholm Major se celebra del 23 de octubre al 7 de noviembre.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFDonde_se_reune_el_publico_Las_principales_plataformas_de_streaming\"><\/span>\u00bfD\u00f3nde se re\u00fane el p\u00fablico? Las principales plataformas de streaming<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Las plataformas de retransmisi\u00f3n en directo son el pan de cada d\u00eda de la industria de los deportes electr\u00f3nicos, especialmente con el COVID-19, que sigue golpeando con fuerza; son accesibles y completamente gratuitas para su uso en ordenadores, televisores o dispositivos m\u00f3viles. Las plataformas m\u00e1s conocidas para ver eventos de esports son Twitch de Amazon y YouTube Gaming &#8211; esta \u00faltima creci\u00f3 en popularidad recientemente, pero Twitch sigue siendo el lugar donde la mayor\u00eda de la gente ama chatear y ver sus eventos favoritos.<\/p>\n<p>La audiencia de los deportes electr\u00f3nicos est\u00e1 muy influenciada por las interacciones en esas plataformas. En Twitch, los organizadores pueden crear encuestas, integrar aplicaciones para diversificar y mantener la atenci\u00f3n de la audiencia, realizar sorteos y mucho m\u00e1s. La cantidad de posibilidades en Twitch explica por qu\u00e9 es tan favorecida y por qu\u00e9 sus n\u00fameros son tan impresionantes.<\/p>\n<p>YouTube Gaming tiene la caracter\u00edstica de crear contenido con capacidad de b\u00fasqueda (VODs o v\u00eddeos de marketing), y su aplicaci\u00f3n de TV es mucho mejor. Adem\u00e1s, la mayor\u00eda de la gente tiene cuentas de Google, que son las que utiliza YouTube; en Twitch, tienes que crear una cuenta y un nombre de usuario si quieres interactuar. YouTube Gaming se centra mucho m\u00e1s en la experiencia de visualizaci\u00f3n, mientras que Twitch se centra m\u00e1s en la comunidad, en las interacciones.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"El_futuro_de_la_industria_de_los_deportes_electronicos\"><\/span>El futuro de la industria de los deportes electr\u00f3nicos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Las proyecciones son tan buenas como pueden ser. Puede que el ritmo de crecimiento del mercado de los deportes electr\u00f3nicos no sea el mismo, pero eso no significa que la industria de los deportes electr\u00f3nicos se vaya a secar; se espera que siga creciendo, desarrollando m\u00e1s disciplinas y creando a\u00fan m\u00e1s razones para que alguien de fuera se una a la fiesta.<\/p>\n<p>El p\u00fablico de los deportes electr\u00f3nicos ve mucho m\u00e1s de un mill\u00f3n de horas al d\u00eda, y las cifras de audiencia siguen creciendo. Statista predice que seremos m\u00e1s de 570 millones de personas en 2024 (imagina el n\u00famero de horas totales vistas). Es una gran oportunidad para aventurarse en la inversi\u00f3n en deportes electr\u00f3nicos, formar parte del equipo de entusiastas de los deportes electr\u00f3nicos, o simplemente seguir su disciplina favorita un poco m\u00e1s de cerca. No querr\u00e1 perderse este barco.<\/p>\n<p>M\u00e1s informaci\u00f3n sobre el valor de la industria de los deportes electr\u00f3nicos: <a href=\"https:\/\/weplayholding.com\/blog\/esports-industry-worth-can-we-translate-into-numbers-the-worth-of-the-esports-industry\/\" target=\"_blank\" rel=\"noopener\">https: <\/a>\/\/weplayholding.com\/blog\/esports-industry-worth-can-we-translate-into-numbers-the-worth-of-the-esports-industry\/  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector de los deportes electr\u00f3nicos siempre ha crecido r\u00e1pidamente y, a pesar de la pandemia del COVID-19, las cifras en 2021 son m\u00e1s altas que nunca. Algunos eventos deportivos clave han contribuido a este \u00e9xito, as\u00ed como una gran cantidad de contenidos creativos que crean expectaci\u00f3n y aumentan los ingresos de los deportes electr\u00f3nicos&#8230;.<\/p>\n","protected":false},"author":96,"featured_media":176935,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27994],"tags":[],"class_list":["post-181518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/posts\/181518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/comments?post=181518"}],"version-history":[{"count":0,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/posts\/181518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/media\/176935"}],"wp:attachment":[{"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/media?parent=181518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/categories?post=181518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socialnewsdaily.com\/es\/wp-json\/wp\/v2\/tags?post=181518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}